{"id":1088,"count":3,"description":"<h2><strong>CBD Food \u2013 Mergulha neste mundo culin\u00e1rio<\/strong><\/h2>\r\nN\u00f3s, na Tom Hemp\u2019s, adoramos comer. Desde snacks e doces a crocantes para os cereais ou o sabor a nozes de \u00f3leo de cannabis delicioso para a tua salada. Na nossa categoria Food existem todos os produtos de cannabis e CBD para tu descobrires.\r\n\r\n\u00c9 novo para ti? Sabe bem? Garantidamente que sim! N\u00f3s sabemos exatamente o que precisas para experienciares o melhor sabor. O teu Gordon Ramsey interior (apenas menos agressivo) est\u00e1 a ficar cada vez mais aborrecido na cozinha? Anseias por algo novo, mas n\u00e3o sabes exatamente o qu\u00ea?\r\n\r\nOs livros de receitas s\u00e3o chatos e a internet apenas mostra receitas extravagantes que, de alguma forma, s\u00e3o demasiado complicadas? Basta navegares um pouco pela nossa variedade colorida de CBD Food e come\u00e7ar a preparar pratos \u00fanicos em tua casa.\r\n<h3><strong>Nunca mais fiques aborrecido na cozinha \u2013 we got your back!<\/strong><\/h3>\r\nPrecisas de um momento de relaxamento depois de um longo dia? Experimenta os nossos deliciosos ch\u00e1s de cannabis Tumeric, Chai e Herbs. O teu smoothie matinal precisa de um pontap\u00e9 de energia extra?\r\n\r\nToma a nossa prote\u00edna pura de cannabis, o Superfood em pessoa. Est\u00e1s a ficar sem ideias para a tua salada e azeite tamb\u00e9m j\u00e1 n\u00e3o \u00e9 a mesma coisa como antigamente? Pimp your salad com \u00f3leo de sementes de cannabis em duas deliciosas variedades. O mundo da CBD Food \u00e9 grande \u2013 atreve-te a experimentar algo novo. J\u00e1 sabes: provar \u00e9 melhor que estudar. You\u2019re welcome.","link":"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/","name":"ALIMENTA\u00c7\u00c3O E NUTRI\u00c7\u00c3O","slug":"food-pt-lifestyle-pt","taxonomy":"product_cat","parent":1163,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o | Tom Hemps<\/title>\n<meta name=\"description\" content=\"Descubra uma variedade deliciosa de ingredientes de c\u00e2nhamo de primeira qualidade, superalimentos e tesouros nutricionais que ir\u00e3o nutrir o seu bem-estar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALIMENTA\u00c7\u00c3O E NUTRI\u00c7\u00c3O Archives\" \/>\n<meta property=\"og:description\" content=\"Descubra uma variedade deliciosa de ingredientes de c\u00e2nhamo de primeira qualidade, superalimentos e tesouros nutricionais que ir\u00e3o nutrir o seu bem-estar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/\" \/>\n<meta property=\"og:site_name\" content=\"Your CBD Shop | Your CBD Brand | born in Berlin\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tomhemps.com\/wp-content\/uploads\/2019\/02\/Tom_Hemps_header_logo-clouds.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/\",\"url\":\"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/\",\"name\":\"Alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o | Tom Hemps\",\"isPartOf\":{\"@id\":\"https:\/\/www.tomhemps.com\/pt-pt\/#website\"},\"description\":\"Descubra uma variedade deliciosa de ingredientes de c\u00e2nhamo de primeira qualidade, superalimentos e tesouros nutricionais que ir\u00e3o nutrir o seu bem-estar.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.tomhemps.com\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lifestyle\",\"item\":\"https:\/\/www.tomhemps.com\/pt-pt\/lifestyle-pt\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ALIMENTA\u00c7\u00c3O E NUTRI\u00c7\u00c3O\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tomhemps.com\/pt-pt\/#website\",\"url\":\"https:\/\/www.tomhemps.com\/pt-pt\/\",\"name\":\"Your CBD Shop | Your CBD Brand | born in Berlin\",\"description\":\"CBD Shop Berlin\",\"publisher\":{\"@id\":\"https:\/\/www.tomhemps.com\/pt-pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tomhemps.com\/pt-pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tomhemps.com\/pt-pt\/#organization\",\"name\":\"Tom Hemp's CBD Shop\",\"alternateName\":\"Tom Hemp's Berlin\",\"url\":\"https:\/\/www.tomhemps.com\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.tomhemps.com\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tomhemps.com\/wp-content\/uploads\/2019\/04\/Logo-2019-e1581413011332.jpg\",\"contentUrl\":\"https:\/\/www.tomhemps.com\/wp-content\/uploads\/2019\/04\/Logo-2019-e1581413011332.jpg\",\"width\":460,\"height\":153,\"caption\":\"Tom Hemp's CBD Shop\"},\"image\":{\"@id\":\"https:\/\/www.tomhemps.com\/pt-pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tomhempsberlin\/\",\"https:\/\/www.instagram.com\/tomhemps_cbd\/\",\"https:\/\/www.youtube.com\/channel\/UCbGxDacLx_DRKyder_zVoNw\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o | Tom Hemps","description":"Descubra uma variedade deliciosa de ingredientes de c\u00e2nhamo de primeira qualidade, superalimentos e tesouros nutricionais que ir\u00e3o nutrir o seu bem-estar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/","og_locale":"pt_PT","og_type":"article","og_title":"ALIMENTA\u00c7\u00c3O E NUTRI\u00c7\u00c3O Archives","og_description":"Descubra uma variedade deliciosa de ingredientes de c\u00e2nhamo de primeira qualidade, superalimentos e tesouros nutricionais que ir\u00e3o nutrir o seu bem-estar.","og_url":"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/","og_site_name":"Your CBD Shop | Your CBD Brand | born in Berlin","og_image":[{"width":1536,"height":1000,"url":"https:\/\/www.tomhemps.com\/wp-content\/uploads\/2019\/02\/Tom_Hemps_header_logo-clouds.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/","url":"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/","name":"Alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o | Tom Hemps","isPartOf":{"@id":"https:\/\/www.tomhemps.com\/pt-pt\/#website"},"description":"Descubra uma variedade deliciosa de ingredientes de c\u00e2nhamo de primeira qualidade, superalimentos e tesouros nutricionais que ir\u00e3o nutrir o seu bem-estar.","breadcrumb":{"@id":"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tomhemps.com\/pt-pt\/food-pt-lifestyle-pt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tomhemps.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Lifestyle","item":"https:\/\/www.tomhemps.com\/pt-pt\/lifestyle-pt\/"},{"@type":"ListItem","position":3,"name":"ALIMENTA\u00c7\u00c3O E NUTRI\u00c7\u00c3O"}]},{"@type":"WebSite","@id":"https:\/\/www.tomhemps.com\/pt-pt\/#website","url":"https:\/\/www.tomhemps.com\/pt-pt\/","name":"Your CBD Shop | Your CBD Brand | born in Berlin","description":"CBD Shop Berlin","publisher":{"@id":"https:\/\/www.tomhemps.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tomhemps.com\/pt-pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.tomhemps.com\/pt-pt\/#organization","name":"Tom Hemp's CBD Shop","alternateName":"Tom Hemp's Berlin","url":"https:\/\/www.tomhemps.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.tomhemps.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.tomhemps.com\/wp-content\/uploads\/2019\/04\/Logo-2019-e1581413011332.jpg","contentUrl":"https:\/\/www.tomhemps.com\/wp-content\/uploads\/2019\/04\/Logo-2019-e1581413011332.jpg","width":460,"height":153,"caption":"Tom Hemp's CBD Shop"},"image":{"@id":"https:\/\/www.tomhemps.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tomhempsberlin\/","https:\/\/www.instagram.com\/tomhemps_cbd\/","https:\/\/www.youtube.com\/channel\/UCbGxDacLx_DRKyder_zVoNw"]}]}},"_links":{"self":[{"href":"https:\/\/www.tomhemps.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/1088"}],"collection":[{"href":"https:\/\/www.tomhemps.com\/pt-pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.tomhemps.com\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.tomhemps.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/1163"}],"wp:post_type":[{"href":"https:\/\/www.tomhemps.com\/pt-pt\/wp-json\/wp\/v2\/product?product_cat=1088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}